


























{"id":1554,"date":"1994-01-27T14:28:54","date_gmt":"1994-01-27T16:28:54","guid":{"rendered":"http:\/\/plas.com.br\/site\/?p=1554"},"modified":"2017-09-02T14:30:20","modified_gmt":"2017-09-02T17:30:20","slug":"reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994","status":"publish","type":"post","link":"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/","title":{"rendered":"Reportagem Ucho de Carvalho sobre Plas &#8211; Caderno Modo de Vida &#8211; Estado de SP- 1994"},"content":{"rendered":"<p>27<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1555\" src=\"http:\/\/plas.com.br\/site\/wp-content\/uploads\/2017\/09\/Reportagem-Plas-Ucho-1995.jpg\" alt=\"\" width=\"1170\" height=\"850\" srcset=\"https:\/\/plas.com.br\/site\/wp-content\/uploads\/2017\/09\/Reportagem-Plas-Ucho-1995.jpg 1170w, https:\/\/plas.com.br\/site\/wp-content\/uploads\/2017\/09\/Reportagem-Plas-Ucho-1995-300x218.jpg 300w, https:\/\/plas.com.br\/site\/wp-content\/uploads\/2017\/09\/Reportagem-Plas-Ucho-1995-768x558.jpg 768w, https:\/\/plas.com.br\/site\/wp-content\/uploads\/2017\/09\/Reportagem-Plas-Ucho-1995-1024x744.jpg 1024w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1549\" src=\"http:\/\/plas.com.br\/site\/wp-content\/uploads\/1994\/08\/Reportagem-Plas-Ucho2-1995.jpg\" alt=\"\" width=\"254\" height=\"236\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>27<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[57,58,56,29],"class_list":["post-1554","post","type-post","status-publish","format-standard","hentry","category-reportagens","tag-bones-plas","tag-chapeus-plas","tag-hucho-de-carvalho","tag-maurice-plas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reportagem Ucho de Carvalho sobre Plas - Caderno Modo de Vida - Estado de SP- 1994 - Plas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reportagem Ucho de Carvalho sobre Plas - Caderno Modo de Vida - Estado de SP- 1994 - Plas\" \/>\n<meta property=\"og:description\" content=\"27\" \/>\n<meta property=\"og:url\" content=\"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/\" \/>\n<meta property=\"og:site_name\" content=\"Plas\" \/>\n<meta property=\"article:published_time\" content=\"1994-01-27T16:28:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-02T17:30:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/plas.com.br\/site\/wp-content\/uploads\/2017\/09\/Reportagem-Plas-Ucho-1995.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/\",\"url\":\"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/\",\"name\":\"Reportagem Ucho de Carvalho sobre Plas - Caderno Modo de Vida - Estado de SP- 1994 - Plas\",\"isPartOf\":{\"@id\":\"https:\/\/plas.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/plas.com.br\/site\/wp-content\/uploads\/2017\/09\/Reportagem-Plas-Ucho-1995.jpg\",\"datePublished\":\"1994-01-27T16:28:54+00:00\",\"dateModified\":\"2017-09-02T17:30:20+00:00\",\"author\":{\"@id\":\"https:\/\/plas.com.br\/site\/#\/schema\/person\/988aa24c6d06c56c1dbddfd9a140b8be\"},\"breadcrumb\":{\"@id\":\"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/#primaryimage\",\"url\":\"https:\/\/plas.com.br\/site\/wp-content\/uploads\/2017\/09\/Reportagem-Plas-Ucho-1995.jpg\",\"contentUrl\":\"https:\/\/plas.com.br\/site\/wp-content\/uploads\/2017\/09\/Reportagem-Plas-Ucho-1995.jpg\",\"width\":1170,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/plas.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reportagem Ucho de Carvalho sobre Plas &#8211; Caderno Modo de Vida &#8211; Estado de SP- 1994\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/plas.com.br\/site\/#website\",\"url\":\"https:\/\/plas.com.br\/site\/\",\"name\":\"Plas\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/plas.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/plas.com.br\/site\/#\/schema\/person\/988aa24c6d06c56c1dbddfd9a140b8be\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/plas.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ac9fdcc401a310d8fe15344af31df3cbcbb8a6596b2e2c6a1f5077cb4e3e85f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ac9fdcc401a310d8fe15344af31df3cbcbb8a6596b2e2c6a1f5077cb4e3e85f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/plas.com.br\/site\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reportagem Ucho de Carvalho sobre Plas - Caderno Modo de Vida - Estado de SP- 1994 - Plas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/","og_locale":"pt_BR","og_type":"article","og_title":"Reportagem Ucho de Carvalho sobre Plas - Caderno Modo de Vida - Estado de SP- 1994 - Plas","og_description":"27","og_url":"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/","og_site_name":"Plas","article_published_time":"1994-01-27T16:28:54+00:00","article_modified_time":"2017-09-02T17:30:20+00:00","og_image":[{"url":"http:\/\/plas.com.br\/site\/wp-content\/uploads\/2017\/09\/Reportagem-Plas-Ucho-1995.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/","url":"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/","name":"Reportagem Ucho de Carvalho sobre Plas - Caderno Modo de Vida - Estado de SP- 1994 - Plas","isPartOf":{"@id":"https:\/\/plas.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/#primaryimage"},"image":{"@id":"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/#primaryimage"},"thumbnailUrl":"http:\/\/plas.com.br\/site\/wp-content\/uploads\/2017\/09\/Reportagem-Plas-Ucho-1995.jpg","datePublished":"1994-01-27T16:28:54+00:00","dateModified":"2017-09-02T17:30:20+00:00","author":{"@id":"https:\/\/plas.com.br\/site\/#\/schema\/person\/988aa24c6d06c56c1dbddfd9a140b8be"},"breadcrumb":{"@id":"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/#primaryimage","url":"https:\/\/plas.com.br\/site\/wp-content\/uploads\/2017\/09\/Reportagem-Plas-Ucho-1995.jpg","contentUrl":"https:\/\/plas.com.br\/site\/wp-content\/uploads\/2017\/09\/Reportagem-Plas-Ucho-1995.jpg","width":1170,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/plas.com.br\/site\/reportagem-ucho-de-carvalho-sobre-plas-caderno-modo-de-vida-estado-de-sp-1994\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/plas.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Reportagem Ucho de Carvalho sobre Plas &#8211; Caderno Modo de Vida &#8211; Estado de SP- 1994"}]},{"@type":"WebSite","@id":"https:\/\/plas.com.br\/site\/#website","url":"https:\/\/plas.com.br\/site\/","name":"Plas","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/plas.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/plas.com.br\/site\/#\/schema\/person\/988aa24c6d06c56c1dbddfd9a140b8be","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/plas.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ac9fdcc401a310d8fe15344af31df3cbcbb8a6596b2e2c6a1f5077cb4e3e85f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ac9fdcc401a310d8fe15344af31df3cbcbb8a6596b2e2c6a1f5077cb4e3e85f?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/plas.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/posts\/1554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/comments?post=1554"}],"version-history":[{"count":2,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/posts\/1554\/revisions"}],"predecessor-version":[{"id":1557,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/posts\/1554\/revisions\/1557"}],"wp:attachment":[{"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/media?parent=1554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/categories?post=1554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/tags?post=1554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}