


























{"id":1443,"date":"2016-06-24T13:48:28","date_gmt":"2016-06-24T16:48:28","guid":{"rendered":"http:\/\/plas.com.br\/site\/?p=1443"},"modified":"2017-05-24T14:32:12","modified_gmt":"2017-05-24T17:32:12","slug":"entrevista-de-maurice-plas","status":"publish","type":"post","link":"https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/","title":{"rendered":"Entrevista de Maurice Plas"},"content":{"rendered":"<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/oAB65cd06TU\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"class_list":["post-1443","post","type-post","status-publish","format-standard","hentry","category-entrevistas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entrevista de Maurice Plas - Plas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista de Maurice Plas - Plas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/\" \/>\n<meta property=\"og:site_name\" content=\"Plas\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-24T16:48:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-24T17:32:12+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/\",\"url\":\"https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/\",\"name\":\"Entrevista de Maurice Plas - Plas\",\"isPartOf\":{\"@id\":\"https:\/\/plas.com.br\/site\/#website\"},\"datePublished\":\"2016-06-24T16:48:28+00:00\",\"dateModified\":\"2017-05-24T17:32:12+00:00\",\"author\":{\"@id\":\"https:\/\/plas.com.br\/site\/#\/schema\/person\/988aa24c6d06c56c1dbddfd9a140b8be\"},\"breadcrumb\":{\"@id\":\"https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/plas.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista de Maurice Plas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/plas.com.br\/site\/#website\",\"url\":\"https:\/\/plas.com.br\/site\/\",\"name\":\"Plas\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/plas.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/plas.com.br\/site\/#\/schema\/person\/988aa24c6d06c56c1dbddfd9a140b8be\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/plas.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ac9fdcc401a310d8fe15344af31df3cbcbb8a6596b2e2c6a1f5077cb4e3e85f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ac9fdcc401a310d8fe15344af31df3cbcbb8a6596b2e2c6a1f5077cb4e3e85f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/plas.com.br\/site\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista de Maurice Plas - Plas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/","og_locale":"pt_BR","og_type":"article","og_title":"Entrevista de Maurice Plas - Plas","og_url":"https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/","og_site_name":"Plas","article_published_time":"2016-06-24T16:48:28+00:00","article_modified_time":"2017-05-24T17:32:12+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/","url":"https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/","name":"Entrevista de Maurice Plas - Plas","isPartOf":{"@id":"https:\/\/plas.com.br\/site\/#website"},"datePublished":"2016-06-24T16:48:28+00:00","dateModified":"2017-05-24T17:32:12+00:00","author":{"@id":"https:\/\/plas.com.br\/site\/#\/schema\/person\/988aa24c6d06c56c1dbddfd9a140b8be"},"breadcrumb":{"@id":"https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/plas.com.br\/site\/entrevista-de-maurice-plas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/plas.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Entrevista de Maurice Plas"}]},{"@type":"WebSite","@id":"https:\/\/plas.com.br\/site\/#website","url":"https:\/\/plas.com.br\/site\/","name":"Plas","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/plas.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/plas.com.br\/site\/#\/schema\/person\/988aa24c6d06c56c1dbddfd9a140b8be","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/plas.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ac9fdcc401a310d8fe15344af31df3cbcbb8a6596b2e2c6a1f5077cb4e3e85f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ac9fdcc401a310d8fe15344af31df3cbcbb8a6596b2e2c6a1f5077cb4e3e85f?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/plas.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/posts\/1443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/comments?post=1443"}],"version-history":[{"count":4,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/posts\/1443\/revisions"}],"predecessor-version":[{"id":1445,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/posts\/1443\/revisions\/1445"}],"wp:attachment":[{"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/media?parent=1443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/categories?post=1443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/tags?post=1443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}