


























{"id":1283,"date":"2014-05-13T15:52:18","date_gmt":"2014-05-13T18:52:18","guid":{"rendered":"http:\/\/plas.com.br\/site\/?p=1283"},"modified":"2016-10-21T18:50:26","modified_gmt":"2016-10-21T20:50:26","slug":"victor-collor-visita-plas","status":"publish","type":"post","link":"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/","title":{"rendered":"Victor Collor visita Plas"},"content":{"rendered":"<p>E com toda essa pegada que venho falando aqui no VICCO sobre Old NY, <a title=\"Old NY Tour\" href=\"http:\/\/www.victorcollor.com.br\/conhecendo-nyc\/nyc-guide\" target=\"_blank\">barbearias<\/a>, filmes de g\u00e2nsgters, <a title=\"Filme : Casino\" href=\"http:\/\/www.victorcollor.com.br\/cultura\/filme-casino\" target=\"_blank\">Scorsese<\/a>, Stones e todas essas coisas que permeiam essas bandas, resolvi ir atr\u00e1s do local, do home made, ou seja, uma busca ao que poder\u00edamos quase chamar de Old SP ou at\u00e9 mesmo Velha SP, explorando os lugares tradicionais dessa cidade que j\u00e1 foi t\u00e3o elegante e hoje se perdeu meio \u00e0 edif\u00edcios modernosos, tudo digital, informalidades, etc.<\/p>\n<p>Muitos de voc\u00eas j\u00e1 devem conhecer o chapeleiro mais famoso da Rua Augusta, Maurice Plas.<br \/>\nMinha primeira vez foi mais ou menos h\u00e1 7 anos, e depois dos dias em NYC que voc\u00eas viram <a title=\"Old NY Tour\" href=\"http:\/\/www.victorcollor.com.br\/conhecendo-nyc\/nyc-guide\" target=\"_blank\">aqui,<\/a> resolvi voltar e ver de perto o que o Sr. Plas junto com seus filhos Robert e Maurice, andam aprontando, e claro com um intuito de comprar um chap\u00e9u. Al\u00e9m disso, a ideia era mostrar para voc\u00eas aqui no VICCO um lugar que aprecio, valorizo e serve de refer\u00eancia para quem gosta e curte esse lifestyle.<\/p>\n<p>Passar de carro por ali j\u00e1 \u00e9 algo que enche os olhos. A antiga fachada toda em madeira e vitrines em vidro recheadas de chap\u00e9u me faz lembrar o que o pessoal da \u201cvelha guarda\u201d sempre me falou sobre o charme que era a Augusta com seus bondes, pessoas elegantes para l\u00e1 e para c\u00e1 e as tradicionais lojas de com\u00e9rcio como cortinas, sof\u00e1s e tecidos. Para encher ainda mais os olhos, por ali \u00e9 capaz de avistar um senhor que chama aten\u00e7\u00e3o pela eleg\u00e2ncia e o garbo (termo que infelizmente anda em desuso nos tecnol\u00f3gicos e informais dias de hoje). Eis Maurice Plas que reina aquele cantinho do hoje chamado Baixo Augusto h\u00e1 mais de 60 anos fazendo chap\u00e9us para os elegantes de ent\u00e3o, os que mant\u00eam o garbo e claro, para a nova gera\u00e7\u00e3o como eu que valoriza essas p\u00e9rolas e riquezas que s\u00f3 o tempo nos presenteia.<br \/>\nEntrar na loja \u00e9 mais legal ainda, \u00e9 uma experi\u00eancia. L\u00e1 est\u00e1 ela parada no tempo, mas n\u00e3o ache que isso \u00e9 uma caracter\u00edstica negativa. Esse final de semana assisti mais uma vez \u00e0 trilogia Poderoso Chef\u00e3o e entrar numa loja dessas \u00e9 como voltar ao tempo e estar vivendo a vida de Vito Corleone quando abre a Genco Imports &amp; Co em Nova Iorque. \u00c9 simplesmente genial\u2026chap\u00e9us pendurados, palet\u00f3s de lapelas largas em manequins \u2013 sim ele faz palet\u00f3 sob medida, costuras ali, rel\u00f3gios antigos a corda ainda funcionando, prateleiras de madeira de verdade e todas essas pequenas coisas que v\u00e3o \u201ccurtindo\u201d com os anos.<\/p>\n<p>O franc\u00eas e belga por op\u00e7\u00e3o, faz chap\u00e9us de todos os tipos, desde o tradicional que eles chamam Borsalino, em refer\u00eancia \u00e0 marca italiana, \u00e0s boinas tipo Ch\u00ea, cap tipo Fidel, chap\u00e9u C\u00f4co, cartolas, \u2026 uma uma infinidade de estilos que s\u00f3 indo l\u00e1 para entender.<br \/>\nPlas utiliza mat\u00e9ria prima natural e n\u00e3o gosta de trabalhar com poli\u00e9ster e essas coisas que a China vem nos \u201cpresenteando\u201d pelo baixo custo. Isso faz com que os chap\u00e9us durem toda vida se bem guardados e cuidados.<br \/>\nAo comprar um, os filhos Robert e Maurice sempre d\u00e3o dicas de como guardar e os cuidados essenciais para a vida longa do bem adquirido.<br \/>\nUm coisa que sempre falo por aqui, seja em um restaurante ou nesses pequenos estabelecimentos, tente trocar uma ideia com quem est\u00e1 te atendendo, tente entender um pouco sobre a ess\u00eancia do lugar, o valor que eles d\u00e3o ao trabalho e esses pequenos detalhes que te faz mais \u201crico\u201d e d\u00e1 mais valor ao bem que voc\u00ea acabou de comprar, al\u00e9m claro de criar uma verdadeira experi\u00eancia de compra e nunca mais esquecer.<\/p>\n<p>Conversei bastante com pai e filhos por mais ou menos uma hora j\u00e1 com a loja fechando e as luzes dos carros j\u00e1 acesas junto com as dos postes e o movimento da \u201cnight\u201d do Baixo Augusta. Plas me contou sobre a sua hist\u00f3ria, a segunda grande guerra, os problemas que passou, um certo desgosto pela sua p\u00e1tria n\u00e3o t\u00e3o amada, Fran\u00e7a, seu amor pela B\u00e9lgica, a falta de eleg\u00e2ncia nos dias de hoje\u2026 jogamos muita conversa fora!<br \/>\nPare um pouco, sente, converse e aprenda com esses que conhecem e sabem da hist\u00f3ria. Falamos tanto ali e aqui querendo sempre ter opini\u00e3o, mas pare de falar um pouco e escute o que essas pessoas t\u00eam a dizer\u2026 isso sim \u00e9 se tornar mais rico!<\/p>\n<p><strong>Servi\u00e7o:<\/strong><br \/>\nPlas<br \/>\nRua Augusta 724 \u2013 Consola\u00e7\u00e3o<br \/>\nTel: 11 3257.9919<br \/>\n<a href=\"http:\/\/www.plas.com.br\/\" target=\"_blank\">www.plas.com.br\u00a0<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13810\" title=\"VC_-08042014_DSF6657\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6657-460x306.jpg\" alt=\"\" width=\"460\" height=\"306\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13811\" title=\"VC_-08042014_DSF6654\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6654-460x689.jpg\" alt=\"\" width=\"460\" height=\"689\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13812\" title=\"VC_-08042014_DSF6644\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6644-460x689.jpg\" alt=\"\" width=\"460\" height=\"689\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13813\" title=\"VC_-08042014_DSF6645\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6645-460x306.jpg\" alt=\"\" width=\"460\" height=\"306\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13814\" title=\"VC_-08042014_DSF6646\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6646-460x689.jpg\" alt=\"\" width=\"460\" height=\"689\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13815\" title=\"VC_-08042014_DSF6647\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6647-460x689.jpg\" alt=\"\" width=\"460\" height=\"689\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13816\" title=\"VC_-08042014_DSF6648\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6648-460x306.jpg\" alt=\"\" width=\"460\" height=\"306\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13817\" title=\"VC_-08042014_DSF6649\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6649-460x306.jpg\" alt=\"\" width=\"460\" height=\"306\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13818\" title=\"VC_-08042014_DSF6650\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6650-460x306.jpg\" alt=\"\" width=\"460\" height=\"306\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13819\" title=\"VC_-08042014_DSF6651\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6651-460x689.jpg\" alt=\"\" width=\"460\" height=\"689\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13820\" title=\"VC_-08042014_DSF6653\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6653-460x690.jpg\" alt=\"\" width=\"460\" height=\"690\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13821\" title=\"VC_-08042014_DSF6658\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6658-460x689.jpg\" alt=\"\" width=\"460\" height=\"689\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13822\" title=\"VC_-08042014_DSF6661\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6661-460x306.jpg\" alt=\"\" width=\"460\" height=\"306\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13824\" title=\"VC_-08042014_DSF6664\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6664-460x306.jpg\" alt=\"\" width=\"460\" height=\"306\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13825\" title=\"VC_-08042014_DSF6665\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6665-460x306.jpg\" alt=\"\" width=\"460\" height=\"306\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13826\" title=\"VC_-08042014_DSF6666\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6666-460x306.jpg\" alt=\"\" width=\"460\" height=\"306\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13823\" title=\"VC_-08042014_DSF6663\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6663-460x306.jpg\" alt=\"\" width=\"460\" height=\"306\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13827\" title=\"VC_-08042014_DSF6659\" src=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6659-460x689.jpg\" alt=\"\" width=\"460\" height=\"689\" \/><\/p>\n<p>Aproveita o inverno chegando e se divirta usando chap\u00e9u.<\/p>\n<p>Mat\u00e9ria fonte: <a href=\"http:\/\/victorcollor.com.br\/moda\/visitando-plas\/\">Victor Collor<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E com toda essa pegada que venho falando aqui no VICCO sobre Old NY, barbearias, filmes de g\u00e2nsgters, Scorsese, Stones e todas essas coisas que permeiam essas bandas, resolvi ir atr\u00e1s do local, do home made, ou seja, uma busca ao que poder\u00edamos quase chamar de Old SP ou at\u00e9 mesmo Velha SP, explorando os [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[27,39,34,40,41],"class_list":["post-1283","post","type-post","status-publish","format-standard","hentry","category-reportagens","tag-chapeus","tag-fashion","tag-moda","tag-plas-chapeus","tag-tradicao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Victor Collor visita Plas - Plas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Victor Collor visita Plas - Plas\" \/>\n<meta property=\"og:description\" content=\"E com toda essa pegada que venho falando aqui no VICCO sobre Old NY, barbearias, filmes de g\u00e2nsgters, Scorsese, Stones e todas essas coisas que permeiam essas bandas, resolvi ir atr\u00e1s do local, do home made, ou seja, uma busca ao que poder\u00edamos quase chamar de Old SP ou at\u00e9 mesmo Velha SP, explorando os [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/\" \/>\n<meta property=\"og:site_name\" content=\"Plas\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-13T18:52:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-21T20:50:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6657-460x306.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/\",\"url\":\"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/\",\"name\":\"Victor Collor visita Plas - Plas\",\"isPartOf\":{\"@id\":\"https:\/\/plas.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6657-460x306.jpg\",\"datePublished\":\"2014-05-13T18:52:18+00:00\",\"dateModified\":\"2016-10-21T20:50:26+00:00\",\"author\":{\"@id\":\"https:\/\/plas.com.br\/site\/#\/schema\/person\/988aa24c6d06c56c1dbddfd9a140b8be\"},\"breadcrumb\":{\"@id\":\"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/#primaryimage\",\"url\":\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6657-460x306.jpg\",\"contentUrl\":\"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6657-460x306.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/plas.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Victor Collor visita Plas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/plas.com.br\/site\/#website\",\"url\":\"https:\/\/plas.com.br\/site\/\",\"name\":\"Plas\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/plas.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/plas.com.br\/site\/#\/schema\/person\/988aa24c6d06c56c1dbddfd9a140b8be\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/plas.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ac9fdcc401a310d8fe15344af31df3cbcbb8a6596b2e2c6a1f5077cb4e3e85f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ac9fdcc401a310d8fe15344af31df3cbcbb8a6596b2e2c6a1f5077cb4e3e85f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/plas.com.br\/site\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Victor Collor visita Plas - Plas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/","og_locale":"pt_BR","og_type":"article","og_title":"Victor Collor visita Plas - Plas","og_description":"E com toda essa pegada que venho falando aqui no VICCO sobre Old NY, barbearias, filmes de g\u00e2nsgters, Scorsese, Stones e todas essas coisas que permeiam essas bandas, resolvi ir atr\u00e1s do local, do home made, ou seja, uma busca ao que poder\u00edamos quase chamar de Old SP ou at\u00e9 mesmo Velha SP, explorando os [&hellip;]","og_url":"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/","og_site_name":"Plas","article_published_time":"2014-05-13T18:52:18+00:00","article_modified_time":"2016-10-21T20:50:26+00:00","og_image":[{"url":"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6657-460x306.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/","url":"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/","name":"Victor Collor visita Plas - Plas","isPartOf":{"@id":"https:\/\/plas.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/#primaryimage"},"image":{"@id":"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/#primaryimage"},"thumbnailUrl":"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6657-460x306.jpg","datePublished":"2014-05-13T18:52:18+00:00","dateModified":"2016-10-21T20:50:26+00:00","author":{"@id":"https:\/\/plas.com.br\/site\/#\/schema\/person\/988aa24c6d06c56c1dbddfd9a140b8be"},"breadcrumb":{"@id":"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/#primaryimage","url":"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6657-460x306.jpg","contentUrl":"http:\/\/www.victorcollor.com.br\/wp-content\/uploads\/2014\/05\/VC_-08042014_DSF6657-460x306.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/plas.com.br\/site\/victor-collor-visita-plas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/plas.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Victor Collor visita Plas"}]},{"@type":"WebSite","@id":"https:\/\/plas.com.br\/site\/#website","url":"https:\/\/plas.com.br\/site\/","name":"Plas","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/plas.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/plas.com.br\/site\/#\/schema\/person\/988aa24c6d06c56c1dbddfd9a140b8be","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/plas.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ac9fdcc401a310d8fe15344af31df3cbcbb8a6596b2e2c6a1f5077cb4e3e85f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ac9fdcc401a310d8fe15344af31df3cbcbb8a6596b2e2c6a1f5077cb4e3e85f?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/plas.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/posts\/1283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/comments?post=1283"}],"version-history":[{"count":1,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/posts\/1283\/revisions"}],"predecessor-version":[{"id":1284,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/posts\/1283\/revisions\/1284"}],"wp:attachment":[{"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/media?parent=1283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/categories?post=1283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plas.com.br\/site\/wp-json\/wp\/v2\/tags?post=1283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}